{"id":3,"date":"2025-03-14T03:48:27","date_gmt":"2025-03-14T03:48:27","guid":{"rendered":"http:\/\/dovapes.com\/?page_id=3"},"modified":"2026-07-13T08:54:34","modified_gmt":"2026-07-13T08:54:34","slug":"politica-sulla-riservatezza","status":"publish","type":"page","link":"https:\/\/dovapes.com\/it\/politica-sulla-riservatezza\/","title":{"rendered":"politica sulla riservatezza"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Chi siamo<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><strong class=\"privacy-policy-tutorial\">Testo suggerito: <\/strong>Il nostro indirizzo web \u00e8: http:\/\/dovapes.com.<\/p>\n\n\n<h2 class=\"wp-block-heading\">Commenti<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><strong class=\"privacy-policy-tutorial\">Testo suggerito: <\/strong>Quando i visitatori lasciano commenti sul sito, raccogliamo i dati mostrati nel modulo dei commenti, oltre all'indirizzo IP del visitatore e alla stringa user agent del browser per aiutare a rilevare lo spam.<\/p>\n\n\n<p class=\"wp-block-paragraph\">Una stringa anonimizzata creata dal tuo indirizzo email (chiamata anche hash) pu\u00f2 essere inviata al servizio Gravatar per verificare se lo stai utilizzando. La politica sulla privacy di Gravatar \u00e8 disponibile qui: https:\/\/automattic.com\/privacy\/. Dopo l'approvazione del tuo commento, la tua immagine del profilo sar\u00e0 visibile pubblicamente nel contesto del commento.<\/p>\n\n\n<h2 class=\"wp-block-heading\">Media<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><strong class=\"privacy-policy-tutorial\">Testo suggerito: <\/strong>Se carichi immagini sul sito, evita di caricare immagini con dati di localizzazione incorporati (EXIF GPS). I visitatori possono scaricare ed estrarre qualsiasi dato di localizzazione dalle immagini presenti sul sito.<\/p>\n\n\n<h2 class=\"wp-block-heading\">Cookie<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><strong class=\"privacy-policy-tutorial\">Testo suggerito: <\/strong>Se lasci un commento sul nostro sito, puoi scegliere di salvare il tuo nome, indirizzo email e sito web nei cookie. Questo ti permette di non dover reinserire i tuoi dati quando lasci un altro commento. Questi cookie durano un anno.<\/p>\n\n\n<p class=\"wp-block-paragraph\">Se visiti la nostra pagina di accesso, impostiamo un cookie temporaneo per verificare se il tuo browser accetta i cookie. Questo cookie non contiene dati personali e viene eliminato alla chiusura del browser.<\/p>\n\n\n<p class=\"wp-block-paragraph\">Quando effettui il login, impostiamo diversi cookie per salvare le tue informazioni di accesso e le preferenze di visualizzazione. I cookie di accesso durano due giorni, quelli delle opzioni di visualizzazione un anno. Se selezioni \"Ricordami\", il login rester\u00e0 attivo per due settimane. Se esci dal tuo account, i cookie di accesso verranno rimossi.<\/p>\n\n\n<p class=\"wp-block-paragraph\">Se modifichi o pubblichi un articolo, un cookie aggiuntivo sar\u00e0 salvato nel tuo browser. Questo cookie non contiene dati personali e indica solo l'ID del post appena modificato. Scade dopo 1 giorno.<\/p>\n\n\n<h2 class=\"wp-block-heading\">Contenuti incorporati da altri siti<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><strong class=\"privacy-policy-tutorial\">Testo suggerito: <\/strong>Gli articoli su questo sito possono includere contenuti incorporati (es. video, immagini, articoli, ecc.). I contenuti incorporati da altri siti si comportano esattamente come se il visitatore avesse visitato direttamente quell'altro sito.<\/p>\n\n\n<p class=\"wp-block-paragraph\">Questi siti potrebbero raccogliere dati su di te, usare cookie, integrare ulteriori strumenti di tracciamento di terze parti e monitorare la tua interazione con i contenuti incorporati, anche se hai un account e sei connesso a quel sito.<\/p>\n\n\n<h2 class=\"wp-block-heading\">Con chi condividiamo i tuoi dati<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><strong class=\"privacy-policy-tutorial\">Testo suggerito: <\/strong>Se richiedi il reset della password, il tuo indirizzo IP sar\u00e0 incluso nell'email di reimpostazione.<\/p>\n\n\n<h2 class=\"wp-block-heading\">Per quanto tempo conserviamo i tuoi dati<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><strong class=\"privacy-policy-tutorial\">Testo suggerito: <\/strong>Se lasci un commento, il commento e i suoi metadati vengono conservati indefinitamente. Questo ci permette di riconoscere e approvare automaticamente eventuali risposte senza doverle mettere in moderazione.<\/p>\n\n\n<p class=\"wp-block-paragraph\">Per gli utenti registrati sul nostro sito (se presenti), conserviamo anche le informazioni personali fornite nel loro profilo. Tutti gli utenti possono vedere, modificare o cancellare le proprie informazioni personali in qualsiasi momento (tranne il nome utente). Gli amministratori del sito possono vedere e modificare queste informazioni.<\/p>\n\n\n<h2 class=\"wp-block-heading\">Quali diritti hai sui tuoi dati<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><strong class=\"privacy-policy-tutorial\">Testo suggerito: <\/strong>Se hai un account su questo sito o hai lasciato commenti, puoi richiedere di ricevere un file esportato con i dati personali che conserviamo su di te, inclusi quelli che ci hai fornito. Puoi anche chiedere la cancellazione di tutti i dati personali che conserviamo. Questo non include i dati che siamo obbligati a mantenere per motivi amministrativi, legali o di sicurezza.<\/p>\n\n\n<h2 class=\"wp-block-heading\">Dove vengono inviati i tuoi dati<\/h2>\n\n\n<p class=\"wp-block-paragraph\"><strong class=\"privacy-policy-tutorial\">Testo suggerito: <\/strong>I commenti dei visitatori possono essere controllati tramite un servizio automatico di rilevamento spam.<\/p>","protected":false},"excerpt":{"rendered":"<p>Who we are Suggested text: Our website address is: http:\/\/dovapes.com. Comments Suggested text: When visitors leave comments on the site we collect the data shown in the comments form, and also the visitor&#8217;s IP address and browser user agent string to help spam detection. An anonymized string created from your email address (also called a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dovapes.com\/it\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dovapes.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dovapes.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dovapes.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dovapes.com\/it\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":0,"href":"https:\/\/dovapes.com\/it\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"wp:attachment":[{"href":"https:\/\/dovapes.com\/it\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}